{"id":7579,"date":"2023-02-23T15:10:33","date_gmt":"2023-02-23T14:10:33","guid":{"rendered":"https:\/\/truck-welt.com\/?post_type=tribe_events&#038;p=7579"},"modified":"2023-03-27T09:40:34","modified_gmt":"2023-03-27T07:40:34","slug":"informationsveranstaltung-texa-konfort-touch-h2-blaster","status":"publish","type":"tribe_events","link":"https:\/\/truck-welt.com\/de\/evento\/informationsveranstaltung-texa-konfort-touch-h2-blaster\/","title":{"rendered":"INFORMATIONSVERANSTALTUNG texa KONFORT TOUCH &#038; H2 BLASTER"},"content":{"rendered":"[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_column_text]Dieses Jahr haben wir von Truckwelt zusammen mit unserem Partner @Texa eine Informations- und Einf\u00fchrungsveranstaltung zu allen Produkten der Linien KONFORT TOUCH und H2 BLASTER organisiert, um Sie \u00fcber alle Neuigkeiten auf dem Laufenden zu halten.<\/p>\n<p>Am Freitag, den 24. M\u00e4rz, um 19.30 Uhr im Sheraton, Via Bruno Buozzi 35 (BZ), mit einem Buffet und einer abschlie\u00dfenden Verlosung f\u00fcr alle Teilnehmer.<\/p>\n<p>Um teilzunehmen, wenden Sie sich bitte an die Nr. 377 5793 022 oder per E-Mail an siegfried.federer@truck-welt.com.<br \/>\nVerpassen Sie es nicht, wir warten auf Sie![\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220; column_border_width=&#8220;none&#8220; column_border_style=&#8220;solid&#8220;][vc_gallery type=&#8220;image_grid&#8220; images=&#8220;7523,7525,7527,7529,7531,7533,7535,7537,7539,7541,7543,7545,7547,7549,7551,7553,7555,7557,7559,7561,7563,7565,7567,7569,7571,7573,7575&#8243; image_grid_loading=&#8220;default&#8220; layout=&#8220;4&#8243; masonry_style=&#8220;true&#8220; item_spacing=&#8220;default&#8220; gallery_style=&#8220;7&#8243; load_in_animation=&#8220;none&#8220; img_size=&#8220;large&#8220;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8220;in_container&#8220; full_screen_row_position=&#8220;middle&#8220; column_margin=&#8220;default&#8220; column_direction=&#8220;default&#8220; column_direction_tablet=&#8220;default&#8220; column_direction_phone=&#8220;default&#8220; scene_position=&#8220;center&#8220; text_color=&#8220;dark&#8220; text_align=&#8220;left&#8220; row_border_radius=&#8220;none&#8220; row_border_radius_applies=&#8220;bg&#8220; overflow=&#8220;visible&#8220; overlay_strength=&#8220;0.3&#8243; gradient_direction=&#8220;left_to_right&#8220; shape_divider_position=&#8220;bottom&#8220; bg_image_animation=&#8220;none&#8220;][vc_column column_padding=&#8220;no-extra-padding&#8220; column_padding_tablet=&#8220;inherit&#8220; column_padding_phone=&#8220;inherit&#8220; column_padding_position=&#8220;all&#8220; column_element_direction_desktop=&#8220;default&#8220; column_element_spacing=&#8220;default&#8220; desktop_text_alignment=&#8220;default&#8220; tablet_text_alignment=&#8220;default&#8220; phone_text_alignment=&#8220;default&#8220; background_color_opacity=&#8220;1&#8243; background_hover_color_opacity=&#8220;1&#8243; column_backdrop_filter=&#8220;none&#8220; column_shadow=&#8220;none&#8220; column_border_radius=&#8220;none&#8220; column_link_target=&#8220;_self&#8220; column_position=&#8220;default&#8220; gradient_direction=&#8220;left_to_right&#8220; overlay_strength=&#8220;0.3&#8243; width=&#8220;1\/1&#8243; tablet_width_inherit=&#8220;default&#8220; animation_type=&#8220;default&#8220; bg_image_animation=&#8220;none&#8220; border_type=&#8220;simple&#8220;&#8230;<\/p>\n","protected":false},"author":8,"featured_media":6733,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[41],"class_list":["post-7579","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","tribe_events_cat-veranstaltungen","cat_veranstaltungen"],"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/tribe_events\/7579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/tribe_events\/7579\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/media\/6733"}],"wp:attachment":[{"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/media?parent=7579"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/tags?post=7579"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/truck-welt.com\/de\/wp-json\/wp\/v2\/tribe_events_cat?post=7579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}